{"id":5485,"date":"2022-03-17T18:10:52","date_gmt":"2022-03-17T17:10:52","guid":{"rendered":"http:\/\/aluxpersur2.com.s111-117.furanet.com\/?page_id=5485"},"modified":"2023-12-14T19:23:39","modified_gmt":"2023-12-14T18:23:39","slug":"celosias","status":"publish","type":"page","link":"https:\/\/aluxpersur.com\/en\/celosias\/","title":{"rendered":"Lattices"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5485\" class=\"elementor elementor-5485\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7325235 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7325235\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de8d53a\" data-id=\"de8d53a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33c063f elementor-widget elementor-widget-heading\" data-id=\"33c063f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Celosias: Fijalux y Plegalux<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aeff1f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aeff1f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9d93238\" data-id=\"9d93238\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e61a1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e5e61a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/en\/celosia-fijalux\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1562\" height=\"1620\" src=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/2022\/03\/celosias_fijalux.png\" class=\"elementor-animation-bounce-out attachment-full size-full wp-image-5490\" alt=\"\" srcset=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/2022\/03\/celosias_fijalux.png 1562w, https:\/\/aluxpersur.com\/wp-content\/uploads\/2022\/03\/celosias_fijalux-1481x1536.png 1481w, https:\/\/aluxpersur.com\/wp-content\/uploads\/2022\/03\/celosias_fijalux-12x12.png 12w\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/en\/celosia-fijalux\/\">Fixalux louvers<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf6d83f\" data-id=\"cf6d83f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd49fcf elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cd49fcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/en\/celosia-plegalux\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1.png\" class=\"elementor-animation-bounce-out attachment-full size-full wp-image-6068\" alt=\"\" srcset=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1.png 1024w, https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1-300x300.png 300w, https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1-150x150.png 150w, https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1-768x768.png 768w, https:\/\/aluxpersur.com\/wp-content\/uploads\/principalb-1024x1024-1-12x12.png 12w\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/en\/celosia-plegalux\/\">Plegalux louvers<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9bb8d59\" data-id=\"9bb8d59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Celosias: Fijalux y Plegalux Celosias Fijalux Celosias Plegalux<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-5485","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/aluxpersur.com\/en\/celosias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fabricante mayorista de Ventanas de PVC, persianas y mosquiteras en Sevilla - Aluxpersur es mayorista dedicado a la fabricaci\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\u00f3n de ventanas de PVC para el profesional.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras\" \/>\n\t\t<meta property=\"og:description\" content=\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/aluxpersur.com\/en\/celosias\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"56\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-03-17T17:10:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-14T18:23:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aluxpersur.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#listItem\",\"name\":\"Celosias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#listItem\",\"position\":2,\"name\":\"Celosias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/#organization\",\"name\":\"Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\",\"description\":\"Aluxpersur es mayorista dedicado a la fabricaci\\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\\u00f3n de ventanas de PVC para el profesional.\",\"url\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/aluxpersur.com\\\/wp-content\\\/uploads\\\/logo-1.jpg\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#organizationLogo\",\"width\":300,\"height\":56},\"image\":{\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#webpage\",\"url\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/\",\"name\":\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras\",\"description\":\"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/celosias\\\/#breadcrumblist\"},\"datePublished\":\"2022-03-17T18:10:52+01:00\",\"dateModified\":\"2023-12-14T19:23:39+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/\",\"name\":\"Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla\",\"description\":\"Aluxpersur es mayorista dedicado a la fabricaci\\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\\u00f3n de ventanas de PVC para el profesional.\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/aluxpersur.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras","description":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","canonical_url":"https:\/\/aluxpersur.com\/en\/celosias\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/aluxpersur.com\/en\/celosias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/aluxpersur.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/aluxpersur.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/aluxpersur.com\/en\/celosias\/#listItem","name":"Celosias"}},{"@type":"ListItem","@id":"https:\/\/aluxpersur.com\/en\/celosias\/#listItem","position":2,"name":"Celosias","previousItem":{"@type":"ListItem","@id":"https:\/\/aluxpersur.com\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/aluxpersur.com\/en\/#organization","name":"Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","description":"Aluxpersur es mayorista dedicado a la fabricaci\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\u00f3n de ventanas de PVC para el profesional.","url":"https:\/\/aluxpersur.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg","@id":"https:\/\/aluxpersur.com\/en\/celosias\/#organizationLogo","width":300,"height":56},"image":{"@id":"https:\/\/aluxpersur.com\/en\/celosias\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/aluxpersur.com\/en\/celosias\/#webpage","url":"https:\/\/aluxpersur.com\/en\/celosias\/","name":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras","description":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/aluxpersur.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/aluxpersur.com\/en\/celosias\/#breadcrumblist"},"datePublished":"2022-03-17T18:10:52+01:00","dateModified":"2023-12-14T19:23:39+01:00"},{"@type":"WebSite","@id":"https:\/\/aluxpersur.com\/en\/#website","url":"https:\/\/aluxpersur.com\/en\/","name":"Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","description":"Aluxpersur es mayorista dedicado a la fabricaci\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\u00f3n de ventanas de PVC para el profesional.","inLanguage":"en-GB","publisher":{"@id":"https:\/\/aluxpersur.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Fabricante mayorista de Ventanas de PVC, persianas y mosquiteras en Sevilla - Aluxpersur es mayorista dedicado a la fabricaci\u00f3n de todo tipo de persianas, celosias, toldos y mosquiteras, junto a la comercializaci\u00f3n de ventanas de PVC para el profesional.","og:type":"article","og:title":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras","og:description":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","og:url":"https:\/\/aluxpersur.com\/en\/celosias\/","og:image":"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg","og:image:secure_url":"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg","og:image:width":300,"og:image:height":56,"article:published_time":"2022-03-17T17:10:52+00:00","article:modified_time":"2023-12-14T18:23:39+00:00","twitter:card":"summary_large_image","twitter:title":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras","twitter:description":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","twitter:image":"https:\/\/aluxpersur.com\/wp-content\/uploads\/logo-1.jpg"},"aioseo_meta_data":{"post_id":"5485","title":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras","description":"Celosias - Fabricante de Ventanas de PVC, persianas y mosquiteras - ALUXPERSUR Sevilla","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-11 18:44:25","updated":"2025-06-04 00:20:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/aluxpersur.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCelosias\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/aluxpersur.com\/en"},{"label":"Celosias","link":"https:\/\/aluxpersur.com\/en\/celosias\/"}],"_links":{"self":[{"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/pages\/5485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/comments?post=5485"}],"version-history":[{"count":28,"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/pages\/5485\/revisions"}],"predecessor-version":[{"id":6312,"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/pages\/5485\/revisions\/6312"}],"wp:attachment":[{"href":"https:\/\/aluxpersur.com\/en\/wp-json\/wp\/v2\/media?parent=5485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}